{"id":457122,"date":"2026-07-13T19:31:16","date_gmt":"2026-07-13T17:31:16","guid":{"rendered":"https:\/\/sagitter.com\/prodotto\/sg-aqupar7-aqu-par-7x12w-rgbwa-uv-ip65\/"},"modified":"2026-07-15T10:32:21","modified_gmt":"2026-07-15T08:32:21","slug":"sg-aqupar7-aqu-par-7x12w-rgbwa-uv-ip65","status":"publish","type":"product","link":"https:\/\/sagitter.com\/it\/prodotto\/sg-aqupar7-aqu-par-7x12w-rgbwa-uv-ip65\/","title":{"rendered":"AQU Par 7X12W RGBWA-UV IP65"},"content":{"rendered":"<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" width=\"740\" style=\"width: 554pt;\">\n<colgroup>\n<col width=\"194\" style=\"mso-width-source:userset;mso-width-alt:6883;width:145pt\">\n<col width=\"546\" style=\"mso-width-source:userset;mso-width-alt:19399;width:409pt\"> <\/colgroup>\n<tbody>\n<tr height=\"58\" style=\"height:43.2pt\">\n<td height=\"58\" class=\"xl66\" width=\"194\" style=\"height:43.2pt;width:145pt\">Sorgente  luminosa<\/td>\n<td class=\"xl65\" width=\"546\" style=\"width:409pt\">7x12W led RGBWA-UV<br \/>    Vita media sorgente LED: >50.000h<br \/>    Frequenza diodi led: >400Hz anti-flicker<\/td>\n<\/tr>\n<tr height=\"19\" style=\"height:14.4pt\">\n<td height=\"19\" class=\"xl66\" style=\"height:14.4pt\">Ottica<\/td>\n<td class=\"xl65\" width=\"546\" style=\"width:409pt\">Angolo di proiezione: 25\u00b0<\/td>\n<\/tr>\n<tr height=\"38\" style=\"height:28.8pt\">\n<td height=\"38\" class=\"xl66\" style=\"height:28.8pt\">Sistema Colori<\/td>\n<td class=\"xl65\" width=\"546\" style=\"width:409pt\">Sorgente LED RGBWA-UV Full  Color<br \/>    Possibilit\u00e0 cromatiche infinite<\/td>\n<\/tr>\n<tr height=\"58\" style=\"height:43.2pt\">\n<td height=\"58\" class=\"xl66\" style=\"height:43.2pt\">Effetti<\/td>\n<td class=\"xl65\" width=\"546\" style=\"width:409pt\">Dimmer lineare 0-100%<br \/>    Strobo regolabile<br \/>    Macro colori richiamabili da DMX<\/td>\n<\/tr>\n<tr height=\"154\" style=\"height:115.2pt\">\n<td height=\"154\" class=\"xl66\" style=\"height:115.2pt\">Controllo e programmazione<\/td>\n<td class=\"xl65\" width=\"546\" style=\"width:409pt\">4 configurazioni DMX  disponibili: 3\/6\/8\/13 canali<br \/>    Key lock password per blocco impostazioni display<br \/>    Modalit\u00e0 Master\/Slave selezionabile<br \/>    Modalit\u00e0 Automatica con possibilit\u00e0 di editare e richiamare 21  programmi<br \/>    Modalit\u00e0 Edit con possibilit\u00e0 di editare e richiamare 11 programmi<br \/>    Modalit\u00e0 Color con la possibilit\u00e0 di richiamare da display 70  programmi<br \/>    11 bilanciamenti temperatura colore<br \/>    4 curve dimmer<\/td>\n<\/tr>\n<tr height=\"134\" style=\"height:100.8pt\">\n<td height=\"134\" class=\"xl66\" style=\"height:100.8pt\">Struttura e corpo mobile<\/td>\n<td class=\"xl65\" width=\"546\" style=\"width:409pt\">Struttura in alluminio  pressofuso<br \/>    Display LCD a colori<br \/>    Vetro temperato frontale<br \/>    Sistema di ancoraggio con doppia staffa per appendimento in quota ed  appoggio a terra<br \/>    Grado di protezione IP65<br \/>    Connessione di segnale XLR 3 Poli DMX IN\/OUT IP65<br \/>    Raffreddamento per convezione senza ventole<\/td>\n<\/tr>\n<tr height=\"77\" style=\"height:57.6pt\">\n<td height=\"77\" class=\"xl66\" style=\"height:57.6pt\">Alimentazione<\/td>\n<td class=\"xl65\" width=\"546\" style=\"width:409pt\">Input Voltage: AC~100-240V,  50\/60 Hz<br \/>    Alimentatore switching universale<br \/>    Potenza Max: 85W @ 230VAC<br \/>    Connessione di alimentazione IN\/OUT IP65<\/td>\n<\/tr>\n<tr height=\"38\" style=\"height:28.8pt\">\n<td height=\"38\" class=\"xl66\" style=\"height:28.8pt\">Peso e dimensioni<\/td>\n<td class=\"xl65\" width=\"546\" style=\"width:409pt\">Peso netto: 3,2 kg<br \/>    Dimensioni: 250x175x230 mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Sorgente luminosa 7x12W led RGBWA-UV Vita media sorgente LED: >50.000h Frequenza diodi led: >400Hz anti-flicker Ottica Angolo di proiezione: 25\u00b0 Sistema Colori Sorgente LED RGBWA-UV Full Color Possibilit\u00e0 cromatiche infinite Effetti Dimmer lineare 0-100% Strobo regolabile Macro colori richiamabili da DMX Controllo e programmazione 4 configurazioni DMX disponibili: 3\/6\/8\/13 canali Key lock password per blocco [&hellip;]<\/p>\n","protected":false},"featured_media":470780,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[26,40],"product_tag":[32],"class_list":["post-457122","product","type-product","status-publish","has-post-thumbnail","product_cat-lighting","product_cat-outdoor-fixtures","product_tag-entertainment","first","instock","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product\/457122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/media\/470780"}],"wp:attachment":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/media?parent=457122"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product_brand?post=457122"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product_cat?post=457122"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product_tag?post=457122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}