{"id":457490,"date":"2026-07-13T19:48:19","date_gmt":"2026-07-13T17:48:19","guid":{"rendered":"https:\/\/sagitter.com\/prodotto\/sg-flbatpluscy2-white-cylindrical-diffuser-height-50cm-f\/"},"modified":"2026-09-01T07:20:01","modified_gmt":"2026-09-01T05:20:01","slug":"sg-flbatpluscy2-white-cylindrical-diffuser-height-50cm-f","status":"publish","type":"product","link":"https:\/\/sagitter.com\/it\/prodotto\/sg-flbatpluscy2-white-cylindrical-diffuser-height-50cm-f\/","title":{"rendered":"WHITE.CYLINDRICAL.DIFFUSER.HEIGHT.50CM.F"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Realizzato in un materiale bianco ottimale per la diffusione della luce emessa dalle sorgenti LED, garantisce una luminosit\u00e0 uniforme e intensa su tutta la sua<\/p>\n<p>superficie. Progettato per essere collegato facilmente al proiettore trasformandolo in una fonte luminosa verticale, che offre straordinari effetti decorativi e<\/p>\n<p>una vasta gamma di applicazioni creative. Questa versione \u00e8 stata pensata per aggiungere un tocco di eleganza e originalit\u00e0 in una variet\u00e0 di contesti esterni,<\/p>\n<p>come giardini, parchi o sentieri, creando percorsi luminosi durante la notte. In contesti interni come saloni o showroom, il tubo agisce come un elemento<\/p>\n<p>decorativo dinamico, capace di adattarsi a temi e atmosfere diverse, da illuminazione soffusa e rilassante a effetti di luce vivaci e colorati.<\/p>\n","protected":false},"featured_media":709327,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[26,42],"product_tag":[32,70],"class_list":["post-457490","product","type-product","status-publish","has-post-thumbnail","product_cat-lighting","product_cat-battery-projectors","product_tag-entertainment","product_tag-lighting-accessory","first","instock","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product\/457490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/media\/709327"}],"wp:attachment":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/media?parent=457490"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product_brand?post=457490"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product_cat?post=457490"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product_tag?post=457490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}