{"id":457594,"date":"2026-07-13T19:53:25","date_gmt":"2026-07-13T17:53:25","guid":{"rendered":"https:\/\/sagitter.com\/prodotto\/sg-strpixbar-barra-pixel-con-50-led-rgb-lunghezza-100cm-ip65\/"},"modified":"2026-09-01T07:26:31","modified_gmt":"2026-09-01T05:26:31","slug":"sg-strpixbar-barra-pixel-con-50-led-rgb-lunghezza-100cm-ip65","status":"publish","type":"product","link":"https:\/\/sagitter.com\/it\/prodotto\/sg-strpixbar-barra-pixel-con-50-led-rgb-lunghezza-100cm-ip65\/","title":{"rendered":"Barra pixel con 50 led RGB lunghezza 100cm IP65"},"content":{"rendered":"<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" width=\"1065\" style=\"width: 799pt;\">\n<colgroup>\n<col width=\"188\" style=\"mso-width-source:userset;mso-width-alt:6875;width:141pt\">\n<col width=\"877\" style=\"mso-width-source:userset;mso-width-alt:32073;width:658pt\"> <\/colgroup>\n<tbody>\n<tr height=\"40\" style=\"height:30.0pt\">\n<td height=\"40\" class=\"xl64\" width=\"188\" style=\"height:30.0pt;width:141pt\">Sorgente  luminosa<\/td>\n<td class=\"xl63\" width=\"877\" style=\"width:658pt\">50 x LED RGB SMD5050<br \/>    Frequenza diodi LED > 400Hz flicker-free<\/td>\n<\/tr>\n<tr height=\"80\" style=\"height:60.0pt\">\n<td height=\"80\" class=\"xl64\" style=\"height:60.0pt\">Ottica<\/td>\n<td class=\"xl63\" width=\"877\" style=\"width:658pt\">Angolo di visione 120\u00b0 x  120\u00b0<br \/>Diffusore trasparente e nero inclusi<br \/>Diffusore bianco tondo e quadrato (venduti separatamente)<br \/>    Passo 20 mm<\/td>\n<\/tr>\n<tr height=\"40\" style=\"height:30.0pt\">\n<td height=\"40\" class=\"xl64\" style=\"height:30.0pt\">Sistema Colori<\/td>\n<td class=\"xl63\" width=\"877\" style=\"width:658pt\">Sorgente led RGB<br \/>    Infinite possibilit\u00e0 cromatiche<\/td>\n<\/tr>\n<tr height=\"20\" style=\"height:15.0pt\">\n<td height=\"20\" class=\"xl64\" style=\"height:15.0pt\">Effetti<\/td>\n<td class=\"xl63\" width=\"877\" style=\"width:658pt\">Controllo singolo pixel<\/td>\n<\/tr>\n<tr height=\"100\" style=\"height:75.0pt\">\n<td height=\"100\" class=\"xl64\" style=\"height:75.0pt\">Controllo e programmazione<\/td>\n<td class=\"xl63\" width=\"877\" style=\"width:658pt\">2 diverse configurazioni DMX  disponibili: 7\/150<br \/>    Protocolli: Art-Net, sACN, RDM tramite box di controllo SG STRPIXBOX16  (venduto separatamente)<br \/>Protocollo dati 16 bit UCS8903<br \/>    Controllo Artnet con Starpix Control 16\/32<\/td>\n<\/tr>\n<tr height=\"120\" style=\"height:90.0pt\">\n<td height=\"120\" class=\"xl64\" style=\"height:90.0pt\">Struttura e corpo mobile<\/td>\n<td class=\"xl63\" width=\"877\" style=\"width:658pt\">Corpo in alluminio pressofuso di  colore nero<br \/>    1 KIT di connessione lineare (incluso)<br \/>    7 diversi KIT di connessione multipla e fissaggio a traliccio (venduti  separatamente)<br \/>    1 base per posizionamento verticale (venduta separatamente)<br \/>    Connettore segnale ed alimentazione Seetronic 4pin XLR IP65 IN\/OUT<br \/>    Grado di protezione IP 65<\/td>\n<\/tr>\n<tr height=\"40\" style=\"height:30.0pt\">\n<td height=\"40\" class=\"xl64\" style=\"height:30.0pt\">Alimentazione<\/td>\n<td class=\"xl63\" width=\"877\" style=\"width:658pt\">Starpix Bar \u00e8 alimentato da  Starpix Control 16\/32<br \/>    Potenza massima: 18 W @ 24VDC<\/td>\n<\/tr>\n<tr height=\"40\" style=\"height:30.0pt\">\n<td height=\"40\" class=\"xl64\" style=\"height:30.0pt\">Peso e dimensioni<\/td>\n<td class=\"xl63\" width=\"877\" style=\"width:658pt\">Peso netto: 1 kg<br \/>    Dimensioni: 100x32x24 mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Sorgente luminosa 50 x LED RGB SMD5050 Frequenza diodi LED > 400Hz flicker-free Ottica Angolo di visione 120\u00b0 x 120\u00b0Diffusore trasparente e nero inclusiDiffusore bianco tondo e quadrato (venduti separatamente) Passo 20 mm Sistema Colori Sorgente led RGB Infinite possibilit\u00e0 cromatiche Effetti Controllo singolo pixel Controllo e programmazione 2 diverse configurazioni DMX disponibili: 7\/150 Protocolli: [&hellip;]<\/p>\n","protected":false},"featured_media":709863,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[26,152],"product_tag":[32],"class_list":["post-457594","product","type-product","status-publish","has-post-thumbnail","product_cat-lighting","product_cat-proiettori-pixel-e-strobo","product_tag-entertainment","first","instock","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product\/457594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/media\/709863"}],"wp:attachment":[{"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/media?parent=457594"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product_brand?post=457594"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product_cat?post=457594"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sagitter.com\/it\/wp-json\/wp\/v2\/product_tag?post=457594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}